{"id":275,"date":"2016-03-05T12:59:04","date_gmt":"2016-03-05T12:59:04","guid":{"rendered":"http:\/\/hedemann-stapler-news.de\/?p=275"},"modified":"2020-09-24T08:49:48","modified_gmt":"2020-09-24T08:49:48","slug":"neues-schiff-und-neue-hafenlogistik-fuer-helgoland","status":"publish","type":"post","link":"https:\/\/hedemann-stapler-news.de\/index.php\/2016\/03\/05\/neues-schiff-und-neue-hafenlogistik-fuer-helgoland\/","title":{"rendered":"Neues Schiff und neue Hafenlogistik f\u00fcr Helgoland"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Hafenlogistik von Hedemann f\u00fcr die Helgoland Reederei Cassen Eils in Cuxhaven<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine neue F\u00e4hre f\u00fcr Helgoland? Das Wort F\u00e4hre ist sicher falsch f\u00fcr das Schiff. Es ist fast wie auf einem kleinen Kreuzfahrtschiff. Luxus f\u00fcr Jedermann und ein sch\u00f6nes Reiseerlebnis. Die \u00dcberfahrt ist auch bei unruhigem Wetter ein tolles Erlebnis, denn durch die Stabilisatoren merkt man so gut wie nichts vom Wellengang. So ist Helgoland zu jeder Zeit eine Reise wert. Aber es kmmt noch besser &#8211; bei der Ankunft legt man direkt am Hafen in Helgoland an. Kein umst\u00e4ndliches Aus- und Einschiffen in kleine wacklige B\u00f6rteboote mehr wie fr\u00fcher, der Gast kommt direkt an Land &#8211; barrierefrei. Das ist der Schritt in ein neues Tourismus-Flair. So suchen es die G\u00e4ste, ruhiger, bequemer, luxuri\u00f6ser. Es macht richtig Spa\u00df, einen Tag mal schnell ebenso nach Helgoland zu fahren. Der Urlaub beginnt schon bei der \u00dcberfahrt. Mit dem neuen Schiff wird jetzt auch die gesamte Versorgung der Insel organisiert. In Cuxhaven und auch auf Helgoland wurde daf\u00fcr eine neue Hafenlogistik installiert. Dort k\u00f6nnen s\u00e4mtliche Waren und alles, was die Insel so braucht, in Container verladen werden. &#8222;Das Hedemann Logistik-Konzept hat uns \u00fcberzeugt&#8220;, so Herr Rafl M\u00fcller von der Reederei Cassen Eils. Es umfasst an Land je einen Gro\u00dfstapler, der Container verladen kann und kleine Elektro-Stapler verladen in der Halle in die Container. Auf Helgoland kommt sogar ein Teleskoplader mit rotierendem Aufbau zum Einsatz. Dieser wird haupts\u00e4chlich als Kran eingesetzt, kann aber auch andere Aufgaben \u00fcbernehmen. &#8222;Wir k\u00f6nnen so noch schneller und flexibler auf alle W\u00fcnsche unserer G\u00e4ste reagieren.&#8220;, so Heiko Ederleh und Knut M\u00fcller von der EMT Hafenlogistik auf Helgoland.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hafenlogistik von Hedemann f\u00fcr die Helgoland Reederei Cassen Eils in Cuxhaven<\/p>\n<p>Eine neue F\u00e4hre f\u00fcr Helgoland? Das Wort F\u00e4hre ist sicher falsch f\u00fcr das Schiff&#8230;<\/p>\n","protected":false},"author":3,"featured_media":256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/posts\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/comments?post=275"}],"version-history":[{"count":2,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/posts\/275\/revisions"}],"predecessor-version":[{"id":571,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/posts\/275\/revisions\/571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/media\/256"}],"wp:attachment":[{"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/media?parent=275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/categories?post=275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hedemann-stapler-news.de\/index.php\/wp-json\/wp\/v2\/tags?post=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}